{"id":1454,"date":"2021-06-09T15:45:31","date_gmt":"2021-06-09T13:45:31","guid":{"rendered":"https:\/\/jip21.com\/siteI\/?post_type=produits&#038;p=1454"},"modified":"2022-01-19T12:26:03","modified_gmt":"2022-01-19T11:26:03","slug":"injection-thermoplastique","status":"publish","type":"produits","link":"https:\/\/www.ixemer.com\/en\/products\/injection-des-plastiques\/injection-thermoplastique\/","title":{"rendered":"INJECTION THERMOPLASTIQUE"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ixemer, la maitrise de la multi-injection thermoplastique<\/h2>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-shaiful-gutenberg-notice-block notice-box notice-default\"><p>Ixemer d\u00e9tient une expertise unique dans le domaine de l\u2019injection thermoplastique. Sp\u00e9cialiste de l\u2019injection multi-mati\u00e8res, notre soci\u00e9t\u00e9 est en mesure de r\u00e9pondre \u00e0 toutes vos demandes et exigences.<br\/>Forts de notre savoir-faire, nous mettons en place des solutions globales et comp\u00e9titives regroupant divers services de pointe\u00a0: conception de vos produits, fabrication de moules,\u00a0injection multi-mati\u00e8res, production en moyennes et grandes s\u00e9ries\u2026<br\/>La soci\u00e9t\u00e9 Ixemer maitrise les\u00a0technologies d\u2019injection thermoplastique\u00a0et \u00e9lastom\u00e8re les plus avanc\u00e9es. Dot\u00e9s d\u2019un parc machine automatis\u00e9, nous prenons en charge chaque \u00e9tape de la conception de vos pi\u00e8ces, quel que soit le mat\u00e9riau souhait\u00e9 \u2013 thermoplastiques \u00ab\u00a0classiques\u00a0\u00bb, thermoplastiques techniques, thermoplastiques \u00e9lastom\u00e8res, silicones\u2026<\/p><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Conception de pi\u00e8ces thermoplastiques pour toutes les industries<\/h2>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-shaiful-gutenberg-notice-block notice-box notice-default\"><p>La performance de notre parc machine et la polyvalence de nos \u00e9quipes nous permettent de r\u00e9pondre aux besoins sp\u00e9cifiques de plusieurs march\u00e9s tels que les secteurs automobile, m\u00e9dical, cosm\u00e9tique, ferroviaire, \u00e9lectrique, ou les domaines du loisir et du b\u00e2timent.<br\/>Professionnels exigeants, nous fournissons \u00e0 nos clients des prestations personnalis\u00e9es, de la conception des prototypes \u00e0 la fabrication de pi\u00e8ces en s\u00e9rie.<br\/>R\u00e9actives, nos \u00e9quipes vous conseillent sur les techniques d\u2019injection thermoplastique\u00a0les plus adapt\u00e9es\u00a0: bi-injection\/tri-injection, injection surmoulage, injection corps creux, combinaison mat\u00e9riaux caoutchouc et plastique\u2026<\/p><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg\" alt=\"\" data-id=\"1603\" data-full-url=\"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg\" data-link=\"https:\/\/jip21.com\/siteI\/marches\/cosmetique-et-medical\/attachment\/ixemer_produit_hd-641-300x300\/\" class=\"wp-image-1603\" srcset=\"https:\/\/www.ixemer.com\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg 300w, https:\/\/www.ixemer.com\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ixemer, la maitrise de la multi-injection thermoplastique Conception de pi\u00e8ces thermoplastiques pour toutes les industries<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1432,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1454","produits","type-produits","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Injection thermoplastique : processus et caract\u00e9ristiques | Ixemer<\/title>\n<meta name=\"description\" content=\"L&#039;injection thermoplastique est une technique qui consiste \u00e0 mettre une mati\u00e8re thermoplastique dans un moule \u00e0 forte pression avec une presse \u00e0 injection.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Injection thermoplastique : processus et caract\u00e9ristiques | Ixemer\" \/>\n<meta property=\"og:description\" content=\"L&#039;injection thermoplastique est une technique qui consiste \u00e0 mettre une mati\u00e8re thermoplastique dans un moule \u00e0 forte pression avec une presse \u00e0 injection.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/\" \/>\n<meta property=\"og:site_name\" content=\"Ixemer Multi Injection thermoplastique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JeantetElastomeres\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T11:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/\",\"url\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/\",\"name\":\"Injection thermoplastique : processus et caract\u00e9ristiques | Ixemer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jip21.com\\\/siteI\\\/wp-content\\\/uploads\\\/Ixemer_Produit_HD-641-300x300-1.jpg\",\"datePublished\":\"2021-06-09T13:45:31+00:00\",\"dateModified\":\"2022-01-19T11:26:03+00:00\",\"description\":\"L'injection thermoplastique est une technique qui consiste \u00e0 mettre une mati\u00e8re thermoplastique dans un moule \u00e0 forte pression avec une presse \u00e0 injection.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jip21.com\\\/siteI\\\/wp-content\\\/uploads\\\/Ixemer_Produit_HD-641-300x300-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jip21.com\\\/siteI\\\/wp-content\\\/uploads\\\/Ixemer_Produit_HD-641-300x300-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/injection-thermoplastique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ixemer.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRODUITS\",\"item\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"INJECTION DES PLASTIQUES\",\"item\":\"https:\\\/\\\/www.ixemer.com\\\/produits\\\/injection-des-plastiques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"INJECTION THERMOPLASTIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ixemer.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ixemer.com\\\/\",\"name\":\"Ixemer Multi Injection\",\"description\":\"Un groupe pour la ma\u00eetrise des \u00e9lastom\u00e8res\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ixemer.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Injection thermoplastique : processus et caract\u00e9ristiques | Ixemer","description":"L'injection thermoplastique est une technique qui consiste \u00e0 mettre une mati\u00e8re thermoplastique dans un moule \u00e0 forte pression avec une presse \u00e0 injection.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/","og_locale":"en_US","og_type":"article","og_title":"Injection thermoplastique : processus et caract\u00e9ristiques | Ixemer","og_description":"L'injection thermoplastique est une technique qui consiste \u00e0 mettre une mati\u00e8re thermoplastique dans un moule \u00e0 forte pression avec une presse \u00e0 injection.","og_url":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/","og_site_name":"Ixemer Multi Injection thermoplastique","article_publisher":"https:\/\/www.facebook.com\/JeantetElastomeres\/","article_modified_time":"2022-01-19T11:26:03+00:00","og_image":[{"url":"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/","url":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/","name":"Injection thermoplastique : processus et caract\u00e9ristiques | Ixemer","isPartOf":{"@id":"https:\/\/www.ixemer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/#primaryimage"},"image":{"@id":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/#primaryimage"},"thumbnailUrl":"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg","datePublished":"2021-06-09T13:45:31+00:00","dateModified":"2022-01-19T11:26:03+00:00","description":"L'injection thermoplastique est une technique qui consiste \u00e0 mettre une mati\u00e8re thermoplastique dans un moule \u00e0 forte pression avec une presse \u00e0 injection.","breadcrumb":{"@id":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/#primaryimage","url":"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg","contentUrl":"https:\/\/jip21.com\/siteI\/wp-content\/uploads\/Ixemer_Produit_HD-641-300x300-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/injection-thermoplastique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ixemer.com\/"},{"@type":"ListItem","position":2,"name":"PRODUITS","item":"https:\/\/www.ixemer.com\/produits\/"},{"@type":"ListItem","position":3,"name":"INJECTION DES PLASTIQUES","item":"https:\/\/www.ixemer.com\/produits\/injection-des-plastiques\/"},{"@type":"ListItem","position":4,"name":"INJECTION THERMOPLASTIQUE"}]},{"@type":"WebSite","@id":"https:\/\/www.ixemer.com\/#website","url":"https:\/\/www.ixemer.com\/","name":"Ixemer Multi Injection","description":"Un groupe pour la ma\u00eetrise des \u00e9lastom\u00e8res","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ixemer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/produits\/1454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/produits"}],"about":[{"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/types\/produits"}],"author":[{"embeddable":true,"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/comments?post=1454"}],"version-history":[{"count":3,"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/produits\/1454\/revisions"}],"predecessor-version":[{"id":1684,"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/produits\/1454\/revisions\/1684"}],"up":[{"embeddable":true,"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/produits\/1432"}],"wp:attachment":[{"href":"https:\/\/www.ixemer.com\/en\/wp-json\/wp\/v2\/media?parent=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}